{"id":1025,"date":"2018-07-08T07:54:31","date_gmt":"2018-07-08T15:54:31","guid":{"rendered":"http:\/\/www.ronwmackenzie.com\/?page_id=1025"},"modified":"2018-07-12T15:59:35","modified_gmt":"2018-07-12T23:59:35","slug":"graduatepaper","status":"publish","type":"page","link":"http:\/\/www.ronwmackenzie.com\/index.php\/graduatepaper\/","title":{"rendered":"Neighborhood urban agricultural hubs: Educating adults to become more self-sufficient, towards a food secure future"},"content":{"rendered":"<a href=\"http:\/\/www.ronwmackenzie.com\/wp-content\/uploads\/2018\/07\/Neighborhood-Urban-Agricultural-Hubs_07082018.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"both\" data-toolbar-fixed=\"on\">Neighborhood Urban Agricultural Hubs_07082018<\/a>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"Layout":"1c","jetpack_post_was_ever_published":false,"footnotes":""},"class_list":["entry","author-ronwmackenzie","post-1025","page","type-page","status-publish"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Neighborhood urban agricultural hubs: Educating adults to become more self-sufficient, towards a food secure future | Ron MacKenzie, MS Ed<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.ronwmackenzie.com\/index.php\/graduatepaper\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neighborhood urban agricultural hubs: Educating adults to become more self-sufficient, towards a food secure future | Ron MacKenzie, MS Ed\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.ronwmackenzie.com\/index.php\/graduatepaper\/\" \/>\n<meta property=\"og:site_name\" content=\"Ron MacKenzie, MS Ed\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ronwmackenzie\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-12T23:59:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@RonWMacKenzie\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.ronwmackenzie.com\/index.php\/graduatepaper\/\",\"url\":\"http:\/\/www.ronwmackenzie.com\/index.php\/graduatepaper\/\",\"name\":\"Neighborhood urban agricultural hubs: Educating adults to become more self-sufficient, towards a food secure future | Ron MacKenzie, MS Ed\",\"isPartOf\":{\"@id\":\"http:\/\/www.ronwmackenzie.com\/#website\"},\"datePublished\":\"2018-07-08T15:54:31+00:00\",\"dateModified\":\"2018-07-12T23:59:35+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/www.ronwmackenzie.com\/index.php\/graduatepaper\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.ronwmackenzie.com\/index.php\/graduatepaper\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.ronwmackenzie.com\/index.php\/graduatepaper\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/www.ronwmackenzie.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neighborhood urban agricultural hubs: Educating adults to become more self-sufficient, towards a food secure future\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.ronwmackenzie.com\/#website\",\"url\":\"http:\/\/www.ronwmackenzie.com\/\",\"name\":\"Ron MacKenzie, MS Ed\",\"description\":\"Sustainable Gardening Educator\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.ronwmackenzie.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neighborhood urban agricultural hubs: Educating adults to become more self-sufficient, towards a food secure future | Ron MacKenzie, MS Ed","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.ronwmackenzie.com\/index.php\/graduatepaper\/","og_locale":"en_US","og_type":"article","og_title":"Neighborhood urban agricultural hubs: Educating adults to become more self-sufficient, towards a food secure future | Ron MacKenzie, MS Ed","og_url":"http:\/\/www.ronwmackenzie.com\/index.php\/graduatepaper\/","og_site_name":"Ron MacKenzie, MS Ed","article_publisher":"https:\/\/www.facebook.com\/ronwmackenzie","article_modified_time":"2018-07-12T23:59:35+00:00","twitter_card":"summary_large_image","twitter_site":"@RonWMacKenzie","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.ronwmackenzie.com\/index.php\/graduatepaper\/","url":"http:\/\/www.ronwmackenzie.com\/index.php\/graduatepaper\/","name":"Neighborhood urban agricultural hubs: Educating adults to become more self-sufficient, towards a food secure future | Ron MacKenzie, MS Ed","isPartOf":{"@id":"http:\/\/www.ronwmackenzie.com\/#website"},"datePublished":"2018-07-08T15:54:31+00:00","dateModified":"2018-07-12T23:59:35+00:00","breadcrumb":{"@id":"http:\/\/www.ronwmackenzie.com\/index.php\/graduatepaper\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.ronwmackenzie.com\/index.php\/graduatepaper\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.ronwmackenzie.com\/index.php\/graduatepaper\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.ronwmackenzie.com\/"},{"@type":"ListItem","position":2,"name":"Neighborhood urban agricultural hubs: Educating adults to become more self-sufficient, towards a food secure future"}]},{"@type":"WebSite","@id":"http:\/\/www.ronwmackenzie.com\/#website","url":"http:\/\/www.ronwmackenzie.com\/","name":"Ron MacKenzie, MS Ed","description":"Sustainable Gardening Educator","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.ronwmackenzie.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"jetpack_shortlink":"https:\/\/wp.me\/P7zcm7-gx","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/www.ronwmackenzie.com\/index.php\/wp-json\/wp\/v2\/pages\/1025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.ronwmackenzie.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.ronwmackenzie.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.ronwmackenzie.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.ronwmackenzie.com\/index.php\/wp-json\/wp\/v2\/comments?post=1025"}],"version-history":[{"count":2,"href":"http:\/\/www.ronwmackenzie.com\/index.php\/wp-json\/wp\/v2\/pages\/1025\/revisions"}],"predecessor-version":[{"id":1029,"href":"http:\/\/www.ronwmackenzie.com\/index.php\/wp-json\/wp\/v2\/pages\/1025\/revisions\/1029"}],"wp:attachment":[{"href":"http:\/\/www.ronwmackenzie.com\/index.php\/wp-json\/wp\/v2\/media?parent=1025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}